{"id":179,"date":"2019-03-14T13:37:48","date_gmt":"2019-03-14T13:37:48","guid":{"rendered":"https:\/\/www.monmouth.edu\/clonet\/?page_id=179"},"modified":"2023-05-24T19:32:04","modified_gmt":"2023-05-24T19:32:04","slug":"photo-gallery","status":"publish","type":"page","link":"https:\/\/www.monmouth.edu\/clonet\/photo-gallery\/","title":{"rendered":"Coastal Lakes Photo Gallery"},"content":{"rendered":"\n<h2 id=\"deal-lake\" class=\"wp-block-heading\">Deal Lake<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"4608\" height=\"3456\" data-id=\"172\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1.jpg\" alt=\"Deal Lake Photo 1\" class=\"wp-image-172\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1.jpg 4608w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-2800x2100.jpg 2800w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-2667x2000.jpg 2667w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 4608px) 100vw, 4608px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"4608\" height=\"3456\" data-id=\"173\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2.jpg\" alt=\"Deal Lake Photo 2\" class=\"wp-image-173\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2.jpg 4608w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-2800x2100.jpg 2800w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-2667x2000.jpg 2667w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-2-150x113.jpg 150w\" sizes=\"auto, (max-width: 4608px) 100vw, 4608px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"176\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3.jpg\" alt=\"Deal Lake Photo 3\" class=\"wp-image-176\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-3-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"178\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4.jpg\" alt=\"Deal Lake Photo 4\" class=\"wp-image-178\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Deal-Lake-Photo-4-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 id=\"other-lakes\" class=\"wp-block-heading\"><strong>Other Lakes<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"208\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1.jpg\" alt=\"Photo of Coastal Lake Tributary\" class=\"wp-image-208\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"209\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2.jpg\" alt=\"Another photo of Coastal Lake Tributary\" class=\"wp-image-209\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Coastal-Lake-Tributary-Photo-2-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"211\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee.jpg\" alt=\"Photo of Lake Takannassee\" class=\"wp-image-211\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Takannassee-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"214\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1.jpg\" alt=\"Shippee's Pond Photo\" class=\"wp-image-214\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"215\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2.jpg\" alt=\"Additional Photo of Shippee's Pond\" class=\"wp-image-215\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Shippees-Pond-Photo-2-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"206\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond.jpg\" alt=\"Photo of Wreck Pond\" class=\"wp-image-206\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Wreck-Pond-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 id=\"lake-health-issues\" class=\"wp-block-heading\"><strong>Lake Health Issues<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"223\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1.jpg\" alt=\"Photo of Lake Health Issues\" class=\"wp-image-223\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Photo-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"224\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond.jpg\" alt=\"Photo shows health issues at Shippee's Pond\" class=\"wp-image-224\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Shippees-Pond-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"221\" src=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact.jpg\" alt=\"Photo shows storm drain impact on coastal lakes\" class=\"wp-image-221\" srcset=\"https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact.jpg 2560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-300x225.jpg 300w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-768x576.jpg 768w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-1024x768.jpg 1024w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-1120x840.jpg 1120w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-560x420.jpg 560w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-280x210.jpg 280w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-320x240.jpg 320w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-640x480.jpg 640w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-1400x1050.jpg 1400w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-360x270.jpg 360w, https:\/\/www.monmouth.edu\/clonet\/wp-content\/uploads\/sites\/721\/2019\/03\/Lake-Health-Issues-Storm-Drain-Impact-150x113.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Deal Lake Other Lakes Lake Health Issues<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mu_eop_enabled":false,"_mu_eop_name":"","_mu_eop_name_override":false,"_mu_eop_description":"","_mu_eop_description_override":false,"_mu_eop_url":"","_mu_eop_url_override":false,"_mu_eop_program_type":"","_mu_eop_educational_credential":"","_mu_eop_time_to_complete":"","_mu_eop_number_of_credits":"","_mu_eop_occupational_category":"","_mu_eop_occupational_category_code":"","_mu_eop_program_prerequisites":"","_mu_eop_application_deadline":"","_mu_eop_application_start_date":"","_mu_eop_start_date":"","_mu_eop_end_date":"","_mu_eop_day_of_week":"","_mu_eop_time_of_day":"","_mu_eop_educational_program_mode":"","_mu_eop_financial_aid_eligible":"","_mu_eop_maximum_enrollment":"","_mu_eop_offers_price":"","_mu_eop_offers_currency":"USD","_mu_eop_offers_price_per":"","_mu_eop_offers_preset":"","_mu_eop_salary_upon_completion":"","_mu_eop_training_salary":"","_mu_eop_recognized_by_name":"","_mu_eop_recognized_by_url":"","_mu_eop_concentrations":"","_mu_eop_identifier_cip":"","_mu_eop_provider_name":"","_mu_eop_provider_name_override":false,"_mu_eop_provider_url":"","_mu_eop_provider_address":"","_mu_eop_provider_city":"","_mu_eop_provider_state":"","_mu_eop_provider_zip":"","_mu_eop_provider_country":"","footnotes":""},"class_list":["post-179","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/pages\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":13,"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/pages\/179\/revisions"}],"predecessor-version":[{"id":685,"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/pages\/179\/revisions\/685"}],"wp:attachment":[{"href":"https:\/\/www.monmouth.edu\/clonet\/wp-json\/wp\/v2\/media?parent=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}